{"id":9405,"date":"2024-04-10T15:35:18","date_gmt":"2024-04-10T15:35:18","guid":{"rendered":"https:\/\/alertasaltillo.com\/?p=9405"},"modified":"2024-04-10T15:35:21","modified_gmt":"2024-04-10T15:35:21","slug":"invitan-a-ninas-y-ninos-a-audiciones-en-el-centro-de-estudios-dancisticos","status":"publish","type":"post","link":"https:\/\/alertasaltillo.com\/index.php\/2024\/04\/10\/invitan-a-ninas-y-ninos-a-audiciones-en-el-centro-de-estudios-dancisticos\/","title":{"rendered":"INVITAN A NI\u00d1AS Y NI\u00d1OS A AUDICIONES EN EL CENTRO DE ESTUDIOS DANC\u00cdSTICOS"},"content":{"rendered":"\n<p><em>En el marco del mes de la danza se ofrece una beca del 100 por ciento a quienes aprueben su audici\u00f3n<\/em><\/p>\n\n\n\n<p>Saltillo, Coahuila de Zaragoza, a 7 de abril de 2024.- En el marco del mes de la danza, el Gobierno Municipal de Saltillo, a trav\u00e9s del Instituto Municipal de Cultura, invita a ni\u00f1as y ni\u00f1os para que realicen su adici\u00f3n a fin de ingresar al Centro de Estudios Danc\u00edsticos en donde se ofrece una beca del 100 por ciento para quienes sean aceptados.<\/p>\n\n\n\n<p>El alcalde Jos\u00e9 Mar\u00eda Fraustro Siller, as\u00ed como la directora del Instituto Municipal de Cultura, Leticia Rodarte Rangel, afirmaron que durante la actual administraci\u00f3n municipal se impulsa la cultura a trav\u00e9s de diferentes vertientes educativas y una de ellas es esta oportunidad de desarrollo.<\/p>\n\n\n\n<p>\u201cEn este gobierno ofrecemos oportunidades de desarrollo con actividades deportivas, culturales y acad\u00e9micas que est\u00e1n al alcance de todos\u201d, afirm\u00f3 Fraustro Siller.<\/p>\n\n\n\n<p>Leticia Rodarte detall\u00f3 que est\u00e1s audiciones que realiza la Coordinaci\u00f3n de Danza est\u00e1n dirigidas a ni\u00f1os y ni\u00f1as de entre 8 y 11 a\u00f1os de edad quienes muestren inter\u00e9s en iniciarse en ballet cl\u00e1sico.<\/p>\n\n\n\n<p>Recalc\u00f3 que las ni\u00f1as y ni\u00f1os que aprueben su audici\u00f3n recibir\u00e1n una beca del 100 por ciento, por lo que no pagar\u00e1n inscripci\u00f3n ni mensualidad en el Centro de Estudios Danc\u00edsticos.<\/p>\n\n\n\n<p>Se inform\u00f3 que para agendar el d\u00eda y la hora de las audiciones, as\u00ed como conocer m\u00e1s detalles al respecto es necesario comunicarse al tel\u00e9fono 844-203-23-58 o al 844-219-95-15.<\/p>\n\n\n\n<p>El Centro de Estudios Danc\u00edsticos del Instituto Municipal de Cultura se ubica en la calle General Cepeda, n\u00famero 367 sur, en la Zona Centro de la ciudad.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En el marco del mes de la danza se ofrece una beca del 100 por ciento a quienes aprueben su audici\u00f3n Saltillo, Coahuila de Zaragoza, a 7 de abril de 2024.- En el marco del mes de la danza, el Gobierno Municipal de Saltillo, a trav\u00e9s del Instituto Municipal de Cultura, invita a ni\u00f1as y [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":9406,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[201],"tags":[],"_links":{"self":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/9405"}],"collection":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/comments?post=9405"}],"version-history":[{"count":1,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/9405\/revisions"}],"predecessor-version":[{"id":9407,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/9405\/revisions\/9407"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/media\/9406"}],"wp:attachment":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/media?parent=9405"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/categories?post=9405"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/tags?post=9405"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}