{"id":27795,"date":"2026-07-15T21:03:28","date_gmt":"2026-07-15T21:03:28","guid":{"rendered":"https:\/\/alertasaltillo.com\/?p=27795"},"modified":"2026-07-15T21:03:31","modified_gmt":"2026-07-15T21:03:31","slug":"seguimos-entregando-apoyos-a-nuestra-gente-con-discapacidad-manolo","status":"publish","type":"post","link":"https:\/\/alertasaltillo.com\/index.php\/2026\/07\/15\/seguimos-entregando-apoyos-a-nuestra-gente-con-discapacidad-manolo\/","title":{"rendered":"SEGUIMOS ENTREGANDO APOYOS A NUESTRA GENTE CON DISCAPACIDAD: MANOLO"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p>&nbsp;&nbsp;&nbsp;<em>Se entregan beneficios a m\u00e1s de 400 personas de La Laguna dentro del programa Veamos por la Discapacidad<\/em><\/p>\n\n\n\n<p>Torre\u00f3n, Coahuila de Zaragoza; a 14 de julio de 2026.- El gobernador Manolo Jim\u00e9nez Salinas, acompa\u00f1ado por Liliana Salinas Vald\u00e9s, presidenta honoraria del DIF Coahuila, as\u00ed como por Miguel \u00c1ngel Riquelme Sol\u00eds, alcalde de Torre\u00f3n, deton\u00f3 en La Laguna la entrega de apoyos econ\u00f3micos del programa \u201cVeamos por la Discapacidad\u201d a m\u00e1s de 400 beneficiarios de los cinco municipios de esta regi\u00f3n de la entidad, quienes recibir\u00e1n 10 mil pesos cada uno por este 2026.<\/p>\n\n\n\n<p>\u00abSeguimos con el programa Veamos la Discapacidad del DIF Coahuila, ahora en La Laguna, donde apoyamos a m\u00e1s de 400 beneficiarios con un apoyo de 10 mil pesos. Adem\u00e1s, agradezco a nuestro alcalde Miguel Angel Riquelme Solis, por sumarse a este gran esfuerzo con 200 becas m\u00e1s para nuestra gente de Torre\u00f3n. Esto es parte de un gran proyecto con el que, a trav\u00e9s de diferentes programas y una inversi\u00f3n de m\u00e1s de 300 MDP, estamos apoyando a miles de personas con discapacidad en todo Coahuila\u00bb, destac\u00f3 el gobernador.<\/p>\n\n\n\n<p>En total en todo el estado, dentro de este programa se est\u00e1n invirtiendo 20 millones de pesos, acciones que son parte del Gran Programa de Inclusi\u00f3n para Personas con Discapacidad, en el cual se invierten 330 millones de pesos en apoyos y beneficios que se incluyen en cinco ejes.<\/p>\n\n\n\n<p>Manolo Jim\u00e9nez se\u00f1al\u00f3 que los apoyos de Veamos por la Discapacidad se estar\u00e1n entregando en todas las regiones de Coahuila, para beneficiar a alrededor de dos mil personas con discapacidad de los 38 municipios del estado.<\/p>\n\n\n\n<p>Record\u00f3 que las acciones del Gran Programa de Inclusi\u00f3n para Personas con Discapacidad tienen qu\u00e9 ver con apoyos econ\u00f3micos, apoyos para terapias, infraestructura, fortalecimiento del programa de movilidad en donde se adquirieron 45 veh\u00edculos Unedif que se repartir\u00e1n en todas las regiones para dar un mejor servicio.<\/p>\n\n\n\n<p>\u201cHoy les estamos entregando una tarjeta a m\u00e1s de 400 beneficiarios, con un apoyo de 10 mil pesos para cada uno de ellos\u201d, inform\u00f3, y a\u00f1adi\u00f3 que en equipo con las y los alcaldes se estar\u00e1 incrementando este programa<\/p>\n\n\n\n<p>En ese sentido, reiter\u00f3 que el trabajo en equipo siempre da mejores resultados, por lo que agradeci\u00f3 a Miguel Riquelme y con \u00e9l, a las y los alcaldes de esta regi\u00f3n Laguna.<\/p>\n\n\n\n<p>Manolo Jim\u00e9nez coment\u00f3 que adem\u00e1s de este tipo de programas, su administraci\u00f3n trabaja en otros temas igual de importantes que tienen que ver con mejorar la calidad de vida de las familias coahuilenses, como son los temas de salud, de educaci\u00f3n, obras y programas sociales, desarrollo econ\u00f3mico, inversiones, empleos y lo m\u00e1s importante, seguridad.<\/p>\n\n\n\n<p>Liliana Salinas Vald\u00e9s mencion\u00f3 que una de las pol\u00edticas del DIF Coahuila es ver la discapacidad de una manera diferente, e inform\u00f3 que est\u00e1n trabajando el tema de discapacidad desde cinco ejes: sensibilizaci\u00f3n, detecci\u00f3n, atenci\u00f3n, movilidad y fortalecimiento.<\/p>\n\n\n\n<p>Reiter\u00f3 que en este programa Veamos por la Discapacidad se invierten 20 millones de pesos y se benefician a dos mil personas de toda la entidad.<\/p>\n\n\n\n<p>Por su parte el alcalde Miguel Riquelme expres\u00f3 que fortalecer la inclusi\u00f3n de las personas con discapacidad y respaldar a las familias que todos los d\u00edas se enfrentan retos extraordinarios con valent\u00eda, amor y determinaci\u00f3n, es una causa profundamente humana.<\/p>\n\n\n\n<p>En ese sentido, reconoci\u00f3 el liderazgo del gobernador Manolo Jim\u00e9nez, de la se\u00f1ora Paola Rodr\u00edguez, presidenta honoraria de Inspira, y sobre todo de la se\u00f1ora Liliana Salinas, quienes, dijo, han impulsado una pol\u00edtica social cercana, sensible, comprometida y sobre todo para quienes m\u00e1s lo necesitan.<\/p>\n\n\n\n<p>\u201cEste programa representa mucho m\u00e1s que un apoyo econ\u00f3mico; representa un acto de justicia social, de sensibilidad y de reconocimiento a miles de coahuilenses que d\u00eda a d\u00eda demuestran que ninguna condici\u00f3n es l\u00edmite cuando existen oportunidades, acompa\u00f1amiento y voluntad para salir adelante\u201d, se\u00f1al\u00f3.<\/p>\n\n\n\n<p>En este evento estuvieron presentes, adem\u00e1s, Gabriel Elizondo P\u00e9rez, senador de la Rep\u00fablica; Celina Bremer, presidenta honoraria de DIF Torre\u00f3n; Ver\u00f3nica Mart\u00ednez, diputada federal; Felipe Gonz\u00e1lez Miranda, diputado local; Mar\u00eda Luisa Valencia Garc\u00eda, magistrada representante del Tribunal Superior de Justicia; Miguel \u00c1ngel Ram\u00edrez L\u00f3pez, alcalde de Matamoros; Brenda Cecilia G\u00fcereca Hern\u00e1ndez, alcaldesa de San Pedro; Jorge Alonso V\u00e9lez Sandoval, alcalde de Viesca; Eliud Felipe Aguirre V\u00e1zquez, secretario de Salud; Alejandro Cepeda Vald\u00e9s, director general de DIF Coahuila; Hugo D\u00e1vila Prado, encargado del despacho de la Secretar\u00eda de Desarrollo Social en La Laguna; Julieta Reyes Mart\u00ednez, beneficiaria de Sierra Mojada.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;&nbsp;&nbsp;Se entregan beneficios a m\u00e1s de 400 personas de La Laguna dentro del programa Veamos por la Discapacidad Torre\u00f3n, Coahuila de Zaragoza; a 14 de julio de 2026.- El gobernador Manolo Jim\u00e9nez Salinas, acompa\u00f1ado por Liliana Salinas Vald\u00e9s, presidenta honoraria del DIF Coahuila, as\u00ed como por Miguel \u00c1ngel Riquelme Sol\u00eds, alcalde de Torre\u00f3n, deton\u00f3 en [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":27796,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[214],"tags":[],"_links":{"self":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/27795"}],"collection":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/comments?post=27795"}],"version-history":[{"count":1,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/27795\/revisions"}],"predecessor-version":[{"id":27797,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/27795\/revisions\/27797"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/media\/27796"}],"wp:attachment":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/media?parent=27795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/categories?post=27795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/tags?post=27795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}