{"id":22041,"date":"2025-12-17T14:05:54","date_gmt":"2025-12-17T14:05:54","guid":{"rendered":"https:\/\/alertasaltillo.com\/?p=22041"},"modified":"2025-12-17T14:05:56","modified_gmt":"2025-12-17T14:05:56","slug":"invita-imm-al-taller-de-permacultura-urbana-de-mi-balcon-al-plato","status":"publish","type":"post","link":"https:\/\/alertasaltillo.com\/index.php\/2025\/12\/17\/invita-imm-al-taller-de-permacultura-urbana-de-mi-balcon-al-plato\/","title":{"rendered":"INVITA IMM AL TALLER DE PERMACULTURA URBANA \u00abDE MI BALC\u00d3N AL PLATO\u00bb"},"content":{"rendered":"\n<p><em>Trabajar\u00e1 para producir alimentos en espacios urbanos<\/em><\/p>\n\n\n\n<p>Saltillo, Coahuila de Zaragoza; 16 de diciembre de 2025.- El Instituto Municipal de las Mujeres invit\u00f3 a las saltillenses a participar en el taller de Permacultura Urbana \u201cDe mi balc\u00f3n al plato\u201d este jueves 18 de diciembre.<\/p>\n\n\n\n<p>En coordinaci\u00f3n con el DIF Saltillo y la Universidad Aut\u00f3noma Agraria Antonio Narro, el taller tiene como objetivo fomentar pr\u00e1cticas sostenibles de producci\u00f3n de alimentos en espacios urbanos.<\/p>\n\n\n\n<p>En horario de 9:00 de la ma\u00f1ana a 1:00 de la tarde, el taller se llevar\u00e1 a cabo en el Auditorio de la Unidad Administrativa, ubicada en la avenida Presidente C\u00e1rdenas 840, Zona Centro.<\/p>\n\n\n\n<p>Ah\u00ed se abordar\u00e1 c\u00f3mo promover el aprovechamiento de balcones, patios y otros espacios reducidos para la creaci\u00f3n de huertos y hortalizas, contribuyendo as\u00ed a la seguridad alimentaria y al cuidado del medio ambiente.<\/p>\n\n\n\n<p>Vanessa Fern\u00e1ndez Tonone, directora del Instituto Municipal de las Mujeres, inform\u00f3 que la capacitaci\u00f3n ser\u00e1 impartida por Lorenzo Alejandro L\u00f3pez Barbosa, especialista de la Universidad Aut\u00f3noma Agraria Antonio Narro, quien compartir\u00e1 conocimientos pr\u00e1cticos sobre permacultura urbana y cultivo de alimentos en casa.<\/p>\n\n\n\n<p>\u201cEste taller introduce los principios fundamentales de la permacultura urbana como un camino hacia la sostenibilidad, la autonom\u00eda alimentaria y el emprendimiento verde\u201d, dijo.<\/p>\n\n\n\n<p>Mencion\u00f3 que est\u00e1 dirigido especialmente a mujeres, amas de casa, emprendedoras y personas sin experiencia en agricultura.<\/p>\n\n\n\n<p>\u201cA trav\u00e9s de din\u00e1micas participativas, actividades pr\u00e1cticas y trabajos colaborativos, las participantes aprender\u00e1n a dise\u00f1ar, construir e instalar un huerto permacultural adaptado a espacios reducidos, utilizando materiales reciclados y t\u00e9cnicas agroecol\u00f3gicas\u201d, refiri\u00f3.<\/p>\n\n\n\n<p>La directora del Instituto Municipal de las Mujeres mencion\u00f3 que el taller es totalmente gratuito.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trabajar\u00e1 para producir alimentos en espacios urbanos Saltillo, Coahuila de Zaragoza; 16 de diciembre de 2025.- El Instituto Municipal de las Mujeres invit\u00f3 a las saltillenses a participar en el taller de Permacultura Urbana \u201cDe mi balc\u00f3n al plato\u201d este jueves 18 de diciembre. En coordinaci\u00f3n con el DIF Saltillo y la Universidad Aut\u00f3noma Agraria [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":22042,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[201],"tags":[],"_links":{"self":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/22041"}],"collection":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/comments?post=22041"}],"version-history":[{"count":1,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/22041\/revisions"}],"predecessor-version":[{"id":22043,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/22041\/revisions\/22043"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/media\/22042"}],"wp:attachment":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/media?parent=22041"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/categories?post=22041"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/tags?post=22041"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}