{"id":21662,"date":"2025-11-29T14:22:33","date_gmt":"2025-11-29T14:22:33","guid":{"rendered":"https:\/\/alertasaltillo.com\/?p=21662"},"modified":"2025-11-29T14:22:37","modified_gmt":"2025-11-29T14:22:37","slug":"son-de-calle-activa-el-espacio-publico-con-cultura-urbana-en-la-casa-del-artesano","status":"publish","type":"post","link":"https:\/\/alertasaltillo.com\/index.php\/2025\/11\/29\/son-de-calle-activa-el-espacio-publico-con-cultura-urbana-en-la-casa-del-artesano\/","title":{"rendered":"\u00abSON DE CALLE\u00bb ACTIVA EL ESPACIO P\u00daBLICO CON CULTURA URBANA EN LA CASA DEL ARTESANO"},"content":{"rendered":"\n<p>Saltillo, Coahuila; 28 de noviembre de 2025.\u2013 El Gobierno del Estado de Coahuila, a trav\u00e9s de la Secretar\u00eda de Cultura, invita a la comunidad a participar en \u201cSon de Calle\u201d, una jornada dedicada al hip hop y a la recuperaci\u00f3n del espacio p\u00fablico, que se llevar\u00e1 a cabo este 29 de noviembre en la Concha Ac\u00fastica de la Casa del Artesano.<\/p>\n\n\n\n<p>De 15:00 a 20:00 horas, el p\u00fablico podr\u00e1 disfrutar una tarde que celebra la energ\u00eda, creatividad y diversidad de la cultura urbana. El programa incluye exhibici\u00f3n de graffiti en vivo, batallas de rap, batallas de beats y competencias de bombas, adem\u00e1s de din\u00e1micas y sorpresas para las y los asistentes.<\/p>\n\n\n\n<p>Esta actividad forma parte del esfuerzo por activar los espacios p\u00fablicos desde el arte y la convivencia comunitaria. La Concha Ac\u00fastica, ubicada en la Casa del Artesano, se convierte nuevamente en un punto de encuentro abierto para las y los amantes del hip hop y para quienes desean acercarse a este movimiento desde su esencia m\u00e1s aut\u00e9ntica.<\/p>\n\n\n\n<p>\u201cSon de Calle\u201d busca generar un ambiente familiar, incluyente y participativo, donde ni\u00f1as, ni\u00f1os, j\u00f3venes y adultos puedan compartir, crear y disfrutar de propuestas art\u00edsticas que fortalecen el tejido social.<\/p>\n\n\n\n<p>El evento se llevar\u00e1 a cabo el viernes 29 de noviembre. La cooperaci\u00f3n es de 50 pesos y la entrada para ni\u00f1as y ni\u00f1os es gratuita.<\/p>\n\n\n\n<p>La Secretar\u00eda de Cultura de Coahuila reitera la invitaci\u00f3n a ser parte de esta celebraci\u00f3n urbana y a seguir construyendo comunidad a trav\u00e9s del arte y el uso activo de nuestros espacios p\u00fablicos.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila; 28 de noviembre de 2025.\u2013 El Gobierno del Estado de Coahuila, a trav\u00e9s de la Secretar\u00eda de Cultura, invita a la comunidad a participar en \u201cSon de Calle\u201d, una jornada dedicada al hip hop y a la recuperaci\u00f3n del espacio p\u00fablico, que se llevar\u00e1 a cabo este 29 de noviembre en la Concha [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21663,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[201],"tags":[],"_links":{"self":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/21662"}],"collection":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/comments?post=21662"}],"version-history":[{"count":1,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/21662\/revisions"}],"predecessor-version":[{"id":21664,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/21662\/revisions\/21664"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/media\/21663"}],"wp:attachment":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/media?parent=21662"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/categories?post=21662"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/tags?post=21662"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}