{"id":21425,"date":"2025-11-20T22:43:49","date_gmt":"2025-11-20T22:43:49","guid":{"rendered":"https:\/\/alertasaltillo.com\/?p=21425"},"modified":"2025-11-20T22:43:51","modified_gmt":"2025-11-20T22:43:51","slug":"disfrutan-saltillenses-de-la-callejoneada-en-el-centro-historico","status":"publish","type":"post","link":"https:\/\/alertasaltillo.com\/index.php\/2025\/11\/20\/disfrutan-saltillenses-de-la-callejoneada-en-el-centro-historico\/","title":{"rendered":"DISFRUTAN SALTILLENSES DE LA CALLEJONEADA EN EL CENTRO HIST\u00d3RICO"},"content":{"rendered":"\n<p><em>Participan las tunas de la UAdeC y estudiantes caracterizados de la Universidad Carolina<\/em><\/p>\n\n\n\n<p>Saltillo, Coahuila de Zaragoza; 19 de noviembre de 2025.- La presidenta honoraria del DIF Saltillo, Luly L\u00f3pez Naranjo, junto a cientos de saltillenses, disfrutaron de la callejoneada \u201cHistorias y Leyendas\u201d que se llev\u00f3 a cabo en el Centro Hist\u00f3rico de Saltillo.<\/p>\n\n\n\n<p>Acompa\u00f1ados por las tunas estudiantiles de la Universidad Aut\u00f3noma de Coahuila (UAdeC) y de estudiantes de la Universidad Carolina caracterizados de personajes hist\u00f3ricos, el recorrido inici\u00f3 en la plaza San Francisco, sobre Ju\u00e1rez y General Cepeda hasta Hidalgo para concluir en el Centro Cultural Vito Alessio Robles.<\/p>\n\n\n\n<p>\u201cTenemos muchos motivos para sentirnos orgullosos de vivir en Saltillo, de presumir nuestra historia y por ello, celebramos la segunda callejoneada del Distrito Centro, que refleja la unidad de hacer las cosas en equipo para difundir nuestras tradiciones, acercando la m\u00fasica, la cultura y nuestras ra\u00edces a las familias saltillenses\u201d, destac\u00f3 la esposa del alcalde Javier D\u00edaz Gonz\u00e1lez.<\/p>\n\n\n\n<p>Mencion\u00f3, que este tipo de eventos se realizan gracias al clima de seguridad de una capital que es considerada entre las mejores a nivel nacional.<\/p>\n\n\n\n<p>Roberto Rojas Oyervides, director de Distrito Centro, se\u00f1al\u00f3 que el Centro Hist\u00f3rico de Saltillo es rico en cultura por las historias y leyendas que lo rodean, cuenta con un recurso arquitect\u00f3nico invaluable como lo es la Catedral, por lo que realizar programas y acciones de este tipo resalta el valor patrimonial de la ciudad.<\/p>\n\n\n\n<p>Agreg\u00f3 que la callejoneada \u201cHistorias y Leyendas\u201d se llev\u00f3 a cabo de manera coordinada entre las Direcciones de Distrito Centro y Turismo, as\u00ed como el Instituto Municipal de Cultura.<\/p>\n\n\n\n<p>En la plaza San Francisco se dio una breve explicaci\u00f3n de las historias y leyendas de personajes importantes como las Se\u00f1oritas Purcell, Benito Ju\u00e1rez y Pancho Villa, entre otros, contando con la participaci\u00f3n de estudiantes de la Universidad Carolina caracterizados.<\/p>\n\n\n\n<p>De ah\u00ed, inici\u00f3 el recorrido con la m\u00fasica de 3 tunas de la Universidad Aut\u00f3noma de Coahuila, por la calle de Ju\u00e1rez hasta Hidalgo, y llegar al Centro Cultural Vito Alessio Robles, donde se cont\u00f3 con un grupo musical.<\/p>\n\n\n\n<p>En el recorrido pasaron por sitios emblem\u00e1ticos como el Recinto de Ju\u00e1rez, la Catedral de Santiago, el Casino de Saltillo, la casa que perteneci\u00f3 a Santos Rojos y Casa Purcell.<\/p>\n\n\n\n<p>En el Centro Cultural Vito Alessio Robles, se llev\u00f3 a cabo una degustaci\u00f3n de bebidas de la regi\u00f3n y m\u00fasica en vivo.<\/p>\n\n\n\n<p>Durante la Callejoneada estuvieron presentes, C\u00e9sar Iv\u00e1n Moreno Aguirre, Jefe de Gabinete y Proyectos Estrat\u00e9gicos del Gobierno Municipal; el rector de la Universidad Carolina, Esteban Garza Fishburn, las directoras Leticia Rodarte Rangel y Lydia Gonz\u00e1lez Rodr\u00edguez, de Cultura y Turismo, respectivamente, adem\u00e1s de la subcoordinadora de Difusi\u00f3n Cultural de la Universidad Aut\u00f3noma de Coahuila, Ana Elena Flores Gonz\u00e1lez; Eduardo Morelos Jim\u00e9nez, regidor presidente de la Comisi\u00f3n de Planeaci\u00f3n, Urbanismo, Obras P\u00fablicas y Centro Hist\u00f3rico y el Presidente de la Comisi\u00f3n de Desarrollo Econ\u00f3mico y Turismo, Ricardo Trevi\u00f1o Salinas.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Participan las tunas de la UAdeC y estudiantes caracterizados de la Universidad Carolina Saltillo, Coahuila de Zaragoza; 19 de noviembre de 2025.- La presidenta honoraria del DIF Saltillo, Luly L\u00f3pez Naranjo, junto a cientos de saltillenses, disfrutaron de la callejoneada \u201cHistorias y Leyendas\u201d que se llev\u00f3 a cabo en el Centro Hist\u00f3rico de Saltillo. Acompa\u00f1ados [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21426,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[201],"tags":[],"_links":{"self":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/21425"}],"collection":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/comments?post=21425"}],"version-history":[{"count":1,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/21425\/revisions"}],"predecessor-version":[{"id":21427,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/21425\/revisions\/21427"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/media\/21426"}],"wp:attachment":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/media?parent=21425"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/categories?post=21425"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/tags?post=21425"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}