{"id":21162,"date":"2025-11-11T15:11:00","date_gmt":"2025-11-11T15:11:00","guid":{"rendered":"https:\/\/alertasaltillo.com\/?p=21162"},"modified":"2025-11-11T15:11:03","modified_gmt":"2025-11-11T15:11:03","slug":"invita-javier-diaz-a-disfrutar-de-la-callejoneada-en-distrito-centro","status":"publish","type":"post","link":"https:\/\/alertasaltillo.com\/index.php\/2025\/11\/11\/invita-javier-diaz-a-disfrutar-de-la-callejoneada-en-distrito-centro\/","title":{"rendered":"INVITA JAVIER D\u00cdAZ A DISFRUTAR DE LA CALLEJONEADA EN DISTRITO CENTRO"},"content":{"rendered":"\n<p>|<em>Se llevar\u00e1 a cabo el mi\u00e9rcoles 19 de noviembre<\/em><\/p>\n\n\n\n<p>Saltillo, Coahuila de Zaragoza; 10 de noviembre de 2025.- El alcalde Javier D\u00edaz Gonz\u00e1lez invit\u00f3 a las familias saltillenses a disfrutar de la Callejoneada \u201cHistorias y Leyendas\u201d que se llevar\u00e1 a cabo el mi\u00e9rcoles 19 de noviembre en Distrito Centro.<\/p>\n\n\n\n<p>\u201cEs la segunda edici\u00f3n que realizamos como Municipio y la primera fue un \u00e9xito total, familias enteras disfrutaron de un ambiente de m\u00fasica, baile y tradici\u00f3n\u201d, dijo.<\/p>\n\n\n\n<p>Mencion\u00f3 que con el apoyo del gobernador Manolo Jim\u00e9nez Salinas, se llevan a cabo este tipo de acciones a fin de promover el turismo y las actividades culturales en el Centro Hist\u00f3rico de la ciudad.<\/p>\n\n\n\n<p>El Alcalde mencion\u00f3 que esta es la segunda edici\u00f3n que se realiza en la administraci\u00f3n municipal, sin embargo, se han replicado m\u00e1s de 15 callejoneadas ciudadanas en el Centro Hist\u00f3rico.<\/p>\n\n\n\n<p>La Callejoneada \u201cHistorias y Leyendas\u201d se llevar\u00e1 a cabo de manera coordinada entre las Direcciones de Distrito Centro y Turismo, as\u00ed como el Instituto Municipal de Cultura, con el apoyo de la Universidad Aut\u00f3noma de Coahuila y la Universidad Carolina.<\/p>\n\n\n\n<p>Iniciar\u00e1 a las 6:45 de la tarde en la plaza San Francisco donde se dar\u00e1 una breve explicaci\u00f3n de las historias y leyendas de personajes importantes como las Se\u00f1oritas Purcell, Benito Ju\u00e1rez y Pancho Villa, entre otros, contando con estudiantes de la Universidad Carolina caracterizados.<\/p>\n\n\n\n<p>El recorrido seguir\u00e1 con la m\u00fasica de 3 tunas de la Universidad Aut\u00f3noma de Coahuila, por la calle de Ju\u00e1rez pasando por General Cepeda y Bravo, para tomar Hidalgo y llegar al Centro Cultural Vito Alessio Robles, donde se contar\u00e1 con un grupo musical.<\/p>\n\n\n\n<p>Durante este recorrido se pasar\u00e1 por sitios emblem\u00e1ticos como la iglesia San Francisco, el Museo Rub\u00e9n Herrera, el Casino, la Catedral de Saltillo, casa Santos Rojo y Casa Purcell.<\/p>\n\n\n\n<p>La Callejoneada se lleva a cabo de manera gratuita. Adem\u00e1s, en el Centro Cultural Vito Alessio Robles,&nbsp;se contar\u00e1 con una degustaci\u00f3n de bebidas de la regi\u00f3n con un costo de recuperaci\u00f3n de $100 pesos.<\/p>\n\n\n\n<p>Para mayores informes o adquirir la pulsera para la degustaci\u00f3n pueden contactarse v\u00eda WhatsApp al tel\u00e9fono 844-327-77-68.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>|Se llevar\u00e1 a cabo el mi\u00e9rcoles 19 de noviembre Saltillo, Coahuila de Zaragoza; 10 de noviembre de 2025.- El alcalde Javier D\u00edaz Gonz\u00e1lez invit\u00f3 a las familias saltillenses a disfrutar de la Callejoneada \u201cHistorias y Leyendas\u201d que se llevar\u00e1 a cabo el mi\u00e9rcoles 19 de noviembre en Distrito Centro. \u201cEs la segunda edici\u00f3n que realizamos [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":21163,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[201],"tags":[],"_links":{"self":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/21162"}],"collection":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/comments?post=21162"}],"version-history":[{"count":1,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/21162\/revisions"}],"predecessor-version":[{"id":21164,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/21162\/revisions\/21164"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/media\/21163"}],"wp:attachment":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/media?parent=21162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/categories?post=21162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/tags?post=21162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}