{"id":19857,"date":"2025-09-22T13:59:36","date_gmt":"2025-09-22T13:59:36","guid":{"rendered":"https:\/\/alertasaltillo.com\/?p=19857"},"modified":"2025-09-22T13:59:38","modified_gmt":"2025-09-22T13:59:38","slug":"disfrutan-saltillenses-del-concierto-mosaico-mexicano-con-la-orquesta-metropolitana","status":"publish","type":"post","link":"https:\/\/alertasaltillo.com\/index.php\/2025\/09\/22\/disfrutan-saltillenses-del-concierto-mosaico-mexicano-con-la-orquesta-metropolitana\/","title":{"rendered":"DISFRUTAN SALTILLENSES DEL CONCIERTO \u00abMOSAICO MEXICANO\u00bb CON LA ORQUESTA METROPOLITANA"},"content":{"rendered":"\n<p><\/p>\n\n\n\n<p><em>Evento se llev\u00f3 a cabo en las instalaciones del Museo de las Aves<\/em><\/p>\n\n\n\n<p>Saltillo, Coahuila de Zaragoza; 20 de septiembre de 2025.- La Orquesta Metropolitana de Saltillo present\u00f3 con \u00e9xito el concierto \u201cMosaico Mexicano\u201d en el que se rindi\u00f3 homenaje a la diversidad y belleza de la m\u00fasica nacional.<\/p>\n\n\n\n<p>Esto fue posible gracias a las obras de Manuel M. Ponce, Eduardo Angulo, y la compositora Nubia Melina Jaime Don Juan.<\/p>\n\n\n\n<p>\u201cNo solo es un concierto, es la celebraci\u00f3n del talento y la creatividad que han dado forma al patrimonio musical de M\u00e9xico\u201d, refiri\u00f3 Leticia Rodarte Rangel, directora del Instituto Municipal de Cultura.<\/p>\n\n\n\n<p>A\u00f1adi\u00f3 adem\u00e1s que este tipo de eventos cuentan con el respaldo total del alcalde Javier D\u00edaz Gonz\u00e1lez, quien tiene como prioridad llevar la cultura a todos los rincones de la ciudad.<\/p>\n\n\n\n<p>El concierto \u201cMosaico Mexicano\u201d fue el s\u00e9ptimo concierto de la temporada de la Orquesta Metropolitana de Saltillo, bajo la direcci\u00f3n de la maestra Natalia Riazanova.<\/p>\n\n\n\n<p>El programa incluy\u00f3 piezas como \u201cEstampas Nocturnas y Estrellitas\u201d, de Manuel M. Ponce; \u201cExtrapidarius\u201d, de Eduardo Angulo; y \u201cA su Merced Don Juan\u201d, a cargo de Nubia Melina Jaime Don Juan.<\/p>\n\n\n\n<p>\u201cMosaico Mexicano\u201d se llev\u00f3 a cabo en las instalaciones del Museo de las Aves, en el Distrito Centro de Saltillo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Evento se llev\u00f3 a cabo en las instalaciones del Museo de las Aves Saltillo, Coahuila de Zaragoza; 20 de septiembre de 2025.- La Orquesta Metropolitana de Saltillo present\u00f3 con \u00e9xito el concierto \u201cMosaico Mexicano\u201d en el que se rindi\u00f3 homenaje a la diversidad y belleza de la m\u00fasica nacional. Esto fue posible gracias a las [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":19858,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[201],"tags":[],"_links":{"self":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/19857"}],"collection":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/comments?post=19857"}],"version-history":[{"count":1,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/19857\/revisions"}],"predecessor-version":[{"id":19859,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/19857\/revisions\/19859"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/media\/19858"}],"wp:attachment":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/media?parent=19857"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/categories?post=19857"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/tags?post=19857"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}