{"id":19765,"date":"2025-09-18T21:16:43","date_gmt":"2025-09-18T21:16:43","guid":{"rendered":"https:\/\/alertasaltillo.com\/?p=19765"},"modified":"2025-09-18T21:16:46","modified_gmt":"2025-09-18T21:16:46","slug":"coahuila-se-convierte-en-la-capital-de-la-fotografia-con-be-alpha-2025","status":"publish","type":"post","link":"https:\/\/alertasaltillo.com\/index.php\/2025\/09\/18\/coahuila-se-convierte-en-la-capital-de-la-fotografia-con-be-alpha-2025\/","title":{"rendered":"COAHUILA SE CONVIERTE EN LA CAPITAL DE LA FOTOGRAF\u00cdA CON BE ALPHA 2025"},"content":{"rendered":"\n<p>&nbsp;&nbsp;&nbsp;<em>Be Alpha Coahuila: innovaci\u00f3n y creatividad para las nuevas generaciones<\/em><\/p>\n\n\n\n<p>Torre\u00f3n, Coahuila; 18 de septiembre de 2025.\u2013 Con gran \u00e9xito inici\u00f3 en la Universidad Aut\u00f3noma de Coahuila el Tour #BeAlphaCoahuila, que en su primer d\u00eda reuni\u00f3 a m\u00e1s de 500 estudiantes interesados en la fotograf\u00eda, el cine y la producci\u00f3n de contenidos digitales.<\/p>\n\n\n\n<p>Este encuentro representa una oportunidad \u00fanica para que los futuros profesionales de estas disciplinas fortalezcan sus conocimientos y se acerquen a la tecnolog\u00eda de vanguardia, al mismo tiempo que ponen en pr\u00e1ctica herramientas que enriquecer\u00e1n su formaci\u00f3n acad\u00e9mica y profesional.<\/p>\n\n\n\n<p>Durante la jornada inaugural, los participantes tuvieron acceso a un taller especializado en el que pudieron aplicar de manera pr\u00e1ctica lo aprendido, experimentando con nuevas t\u00e9cnicas y propuestas creativas. En esta primera sesi\u00f3n, Erick Vicino, fot\u00f3grafo conceptual y artista visual, fue el encargado de compartir su experiencia y conocimientos con los estudiantes, motiv\u00e1ndolos a explorar nuevas formas de narrar y capturar im\u00e1genes, reforzando as\u00ed la relevancia de este tipo de actividades en el desarrollo del talento joven.<\/p>\n\n\n\n<p>El Gobierno del Estado de Coahuila, a trav\u00e9s de la Secretar\u00eda de Cultura, en colaboraci\u00f3n con Sony, impulsa esta segunda edici\u00f3n de Be Alpha Coahuila, un espacio que fortalece el desarrollo profesional de los artistas de la lente y acerca a los j\u00f3venes a las \u00faltimas tendencias en fotograf\u00eda y creaci\u00f3n de contenido digital.<\/p>\n\n\n\n<p>En representaci\u00f3n de la Secretaria de Cultura, Blanca Azucena Ruvalcaba Cabello, Directora de Programas Culturales y Gesti\u00f3n de Recursos, expres\u00f3:<\/p>\n\n\n\n<p>\u201cEs un gusto anunciar la realizaci\u00f3n de la segunda edici\u00f3n de Be Alpha Coahuila, un encuentro que confirma la importancia de sumar esfuerzos entre la Secretar\u00eda de Cultura de Coahuila y una empresa l\u00edder como Sony. Gracias a esta colaboraci\u00f3n, hoy podemos ofrecer a las y los j\u00f3venes de Coahuila una plataforma de aprendizaje y profesionalizaci\u00f3n en el fascinante mundo de la fotograf\u00eda y la creaci\u00f3n de contenido digital, con el apoyo de importantes instituciones educativas aliadas a esta causa\u201d.<\/p>\n\n\n\n<p>El tour #BeAlphaCoahuila recorrer\u00e1 del 18 al 27 de septiembre dos ciudades clave del estado, con el objetivo de atender a cerca de 2,400 alumnos de carreras relacionadas con la comunicaci\u00f3n, el cine, las artes pl\u00e1sticas y el dise\u00f1o gr\u00e1fico.<\/p>\n\n\n\n<p>En esta edici\u00f3n participan como ponentes Alex G\u00fcemes y Erik Vicino, artistas de reconocimiento internacional. G\u00fcemes, director de fotograf\u00eda, ha trabajado con Netflix y Google, adem\u00e1s de dirigir producciones cinematogr\u00e1ficas de gran nivel; mientras que Vicino ha expuesto su obra en espacios de prestigio internacional como el Museo del Louvre en Par\u00eds y el Instituto Cervantes en Tokio, consolid\u00e1ndose como un referente de la fotograf\u00eda conceptual y de innovaci\u00f3n.<\/p>\n\n\n\n<p>Blanca Ruvalcaba subray\u00f3 adem\u00e1s el respaldo del Gobernador Manolo Jim\u00e9nez Salinas, destacando que \u201ceste proyecto no ser\u00eda posible sin su visi\u00f3n e inter\u00e9s genuino en impulsar el desarrollo cultural de la juventud coahuilense. Con Be Alpha abrimos espacios de encuentro y capacitaci\u00f3n que fortalecen a nuestra comunidad de fot\u00f3grafos y creadores visuales en el estado\u201d.<\/p>\n\n\n\n<p>El evento cuenta con el apoyo de instituciones de educaci\u00f3n superior como la Universidad Aut\u00f3noma de Coahuila, la Universidad Aut\u00f3noma de La Laguna, la Universidad Iberoamericana, Casa La Morelos en Torre\u00f3n, la Universidad La Salle, la Universidad Aut\u00f3noma del Noreste, la UVM y la Universidad Carolina.<\/p>\n\n\n\n<p>De esta manera, Be Alpha Coahuila se proyecta como una experiencia enriquecedora para estudiantes, fot\u00f3grafos y entusiastas de la imagen, que coloca a Coahuila en el mapa de la innovaci\u00f3n visual y abre nuevas oportunidades para miles de j\u00f3venes creadores.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp;&nbsp;&nbsp;Be Alpha Coahuila: innovaci\u00f3n y creatividad para las nuevas generaciones Torre\u00f3n, Coahuila; 18 de septiembre de 2025.\u2013 Con gran \u00e9xito inici\u00f3 en la Universidad Aut\u00f3noma de Coahuila el Tour #BeAlphaCoahuila, que en su primer d\u00eda reuni\u00f3 a m\u00e1s de 500 estudiantes interesados en la fotograf\u00eda, el cine y la producci\u00f3n de contenidos digitales. Este encuentro [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":19766,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[201],"tags":[],"_links":{"self":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/19765"}],"collection":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/comments?post=19765"}],"version-history":[{"count":1,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/19765\/revisions"}],"predecessor-version":[{"id":19767,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/19765\/revisions\/19767"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/media\/19766"}],"wp:attachment":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/media?parent=19765"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/categories?post=19765"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/tags?post=19765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}