{"id":12459,"date":"2024-11-06T00:04:50","date_gmt":"2024-11-06T00:04:50","guid":{"rendered":"https:\/\/alertasaltillo.com\/?p=12459"},"modified":"2024-11-06T00:04:54","modified_gmt":"2024-11-06T00:04:54","slug":"invitan-a-visitar-el-altar-de-muertos-en-palacio-de-gobierno","status":"publish","type":"post","link":"https:\/\/alertasaltillo.com\/index.php\/2024\/11\/06\/invitan-a-visitar-el-altar-de-muertos-en-palacio-de-gobierno\/","title":{"rendered":"INVITAN A VISITAR EL ALTAR DE MUERTOS EN PALACIO DE GOBIERNO"},"content":{"rendered":"\n<p>Saltillo, Coahuila de Zaragoza; a 01 de noviembre de 2024.- Como parte de las acciones encaminadas a preservar y disfrutar de nuestras tradiciones en familia, el Gobierno del Estado invita a la ciudadan\u00eda a visitar el Altar de Muertos que se instal\u00f3 en el patio central del Palacio de Gobierno, el cual est\u00e1 dedicado a los ex presidentes coahuilenses.<\/p>\n\n\n\n<p>Este Altar de Muertos se puede visitar de manera gratuita en un horario de 9:00 a 21:00 horas hasta el domingo 3 de noviembre.<\/p>\n\n\n\n<p>Para el gobierno de Manolo Jim\u00e9nez, el fomentar este tipo de eventos, como las celebraciones por el D\u00eda de Muertos, es una gran apuesta para la sana convivencia entre las familias, y que vivan nuestras tradiciones en completa paz y tranquilidad.<\/p>\n\n\n\n<p>Reiter\u00f3 que una s\u00f3lida uni\u00f3n familiar es la base para que, en equipo, las y los coahuilenses podamos llevar a nuestro estado al siguiente nivel.<\/p>\n\n\n\n<p>Este Altar de Muertos est\u00e1 dedicado a los cinco ex presidentes de Coahuila: Melchor M\u00fazquiz, Francisco I. Madero, Venustiano Carranza, Eulalio Guti\u00e9rrez y Roque Victoriano Gonz\u00e1lez Garza.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Saltillo, Coahuila de Zaragoza; a 01 de noviembre de 2024.- Como parte de las acciones encaminadas a preservar y disfrutar de nuestras tradiciones en familia, el Gobierno del Estado invita a la ciudadan\u00eda a visitar el Altar de Muertos que se instal\u00f3 en el patio central del Palacio de Gobierno, el cual est\u00e1 dedicado a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":12460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[201],"tags":[],"_links":{"self":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/12459"}],"collection":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/comments?post=12459"}],"version-history":[{"count":1,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/12459\/revisions"}],"predecessor-version":[{"id":12461,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/12459\/revisions\/12461"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/media\/12460"}],"wp:attachment":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/media?parent=12459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/categories?post=12459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/tags?post=12459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}