{"id":10684,"date":"2024-07-09T20:37:10","date_gmt":"2024-07-09T20:37:10","guid":{"rendered":"https:\/\/alertasaltillo.com\/?p=10684"},"modified":"2024-07-09T20:37:13","modified_gmt":"2024-07-09T20:37:13","slug":"arrancara-fina-con-desfile-y-mariachi-gama-1000","status":"publish","type":"post","link":"https:\/\/alertasaltillo.com\/index.php\/2024\/07\/09\/arrancara-fina-con-desfile-y-mariachi-gama-1000\/","title":{"rendered":"ARRANCAR\u00c1 FINA CON DESFILE Y MARIACHI GAMA 1000"},"content":{"rendered":"\n<p><em>Invita Alcalde a disfrutar en familia Fiesta Internacional de las Artes por el 447 aniversario de Saltillo<\/em><\/p>\n\n\n\n<p>Saltillo, Coahuila de Zaragoza, a 8 de julio de 2024.- El alcalde Jos\u00e9 Mar\u00eda Fraustro Siller invit\u00f3 a la ciudadan\u00eda a disfrutar en familia los eventos preparados en la Fiesta Internacional de las Artes, FINA, Saltillo 447.<\/p>\n\n\n\n<p>Ser\u00e1 este pr\u00f3ximo domingo 14 de julio cuando arranque oficialmente la FINA con un desfile multidisciplinario encabezado por el propio presidente municipal, autoridades y artistas.<\/p>\n\n\n\n<p>El desfile iniciar\u00e1 a las 18:00 horas en el bulevar Venustiano Carranza, esquina con Chihuahua, y el recorrido ser\u00e1 de norte a sur por la calle Ignacio Allende hasta llegar a la plaza Nueva Tlaxcala.<\/p>\n\n\n\n<p>Participar\u00e1n direcciones del Ayuntamiento de Saltillo, Secretar\u00eda de Cultura de Coahuila, Academia de Polic\u00eda de Saltillo, Uni\u00f3n de Asociaciones de Charros del Estado de Coahuila, Asociaci\u00f3n Estatal de Rodeo de Coahuila, Club de Rodeo Regi\u00f3n Sureste, Universidad Aut\u00f3noma de Coahuila, Danzas de la Calle, Academia de Porristas Wolverines, matlachines, gremio de payasos, Comisi\u00f3n de Box y Lucha Libre de Saltillo, Motoclub MC Cherokees Saltillo y Foringas Truck Club Saltillo.<\/p>\n\n\n\n<p>Tambi\u00e9n el domingo 14 de julio, como parte de las actividades de arranque de la FINA 447, se presentar\u00e1 el famoso Mariachi Gama 1000 en punto de las 20:00 horas en Plaza de Armas.<\/p>\n\n\n\n<p>El alcalde Chema Fraustro se\u00f1al\u00f3 que la Fiesta Internacional de las Artes se realizar\u00e1 del 14 al 25 de julio, para celebrar los 447 a\u00f1os de la fundaci\u00f3n de Saltillo.<\/p>\n\n\n\n<p>\u201cTendremos 12 d\u00edas de fiesta con la participaci\u00f3n de 2 mil 975 artistas saltillenses, nacionales e internacionales en 139 actividades, todas gratuitas para la ciudadan\u00eda\u201d, dijo.<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Invita Alcalde a disfrutar en familia Fiesta Internacional de las Artes por el 447 aniversario de Saltillo Saltillo, Coahuila de Zaragoza, a 8 de julio de 2024.- El alcalde Jos\u00e9 Mar\u00eda Fraustro Siller invit\u00f3 a la ciudadan\u00eda a disfrutar en familia los eventos preparados en la Fiesta Internacional de las Artes, FINA, Saltillo 447. Ser\u00e1 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":10685,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[201],"tags":[],"_links":{"self":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/10684"}],"collection":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/comments?post=10684"}],"version-history":[{"count":1,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/10684\/revisions"}],"predecessor-version":[{"id":10686,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/posts\/10684\/revisions\/10686"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/media\/10685"}],"wp:attachment":[{"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/media?parent=10684"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/categories?post=10684"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alertasaltillo.com\/index.php\/wp-json\/wp\/v2\/tags?post=10684"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}